{"id":1046,"date":"2024-11-18T09:56:51","date_gmt":"2024-11-18T08:56:51","guid":{"rendered":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/?p=1046"},"modified":"2026-06-17T13:47:37","modified_gmt":"2026-06-17T11:47:37","slug":"diazepam-y-alcohol","status":"publish","type":"post","link":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/","title":{"rendered":"Diazepam y Alcohol"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Efectos aditivos:<\/strong> Tanto el diazepam como el alcohol son depresores del sistema nervioso central, por lo que cuando se combinan, sus efectos sedantes y depresores se potencian. Esto puede llevar a una sedaci\u00f3n excesiva, somnolencia profunda y una grave depresi\u00f3n respiratoria, lo que puede ser fatal si no se controla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Riesgo de sobredosis:<\/strong> La depresi\u00f3n respiratoria es una de las consecuencias m\u00e1s graves de esta combinaci\u00f3n. Tanto el alcohol como el diazepam pueden disminuir la capacidad del cuerpo para respirar adecuadamente. La combinaci\u00f3n de ambos aumenta el riesgo de fallo respiratorio, que puede llevar a la muerte en casos extremos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>P\u00e9rdida de control: <\/strong>Los efectos de sedaci\u00f3n y somnolencia pueden llevar a p\u00e9rdida de coordinaci\u00f3n motora, dificultad para pensar con claridad y una falta de juicio. Esto aumenta considerablemente el riesgo de accidentes, ca\u00eddas o comportamientos peligrosos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectos aditivos: Tanto el diazepam como el alcohol son depresores del sistema nervioso central, por lo que cuando se combinan, sus efectos sedantes y depresores se potencian. Esto puede llevar a una sedaci\u00f3n excesiva, somnolencia profunda y una grave depresi\u00f3n respiratoria, lo que puede ser fatal si no se controla. Riesgo de sobredosis: La depresi\u00f3n <a href=\"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/\" class=\"more-link\">&#8230;<span class=\"screen-reader-text\">  Diazepam y Alcohol<\/span><\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"sustancias":[4,55],"riesgo":[16],"class_list":["post-1046","post","type-post","status-publish","format-standard","hentry","category-depresoras","sustancias-alcohol","sustancias-diazepam","riesgo-peligroso"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfEs peligroso mezclar Diazepam y Alcohol? | Drogopedia<\/title>\n<meta name=\"description\" content=\"Mezclar Diazepam y Alcohol es muy peligroso para tu salud. Consulta efectos, interacciones y precauciones en la gu\u00eda Mezclas y Riesgos de Drogopedia.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfEs peligroso mezclar Diazepam y Alcohol? | Drogopedia\" \/>\n<meta property=\"og:description\" content=\"Mezclar Diazepam y Alcohol es muy peligroso para tu salud. Consulta efectos, interacciones y precauciones en la gu\u00eda Mezclas y Riesgos de Drogopedia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/\" \/>\n<meta property=\"og:site_name\" content=\"Drogopedia: Mezclas y Riesgos - Gu\u00eda Interactiva\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-18T08:56:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-17T11:47:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-content\/uploads\/2024\/08\/1200x675.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Drogopedia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"drogo_nsue\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfEs peligroso mezclar Diazepam y Alcohol? | Drogopedia","description":"Mezclar Diazepam y Alcohol es muy peligroso para tu salud. Consulta efectos, interacciones y precauciones en la gu\u00eda Mezclas y Riesgos de Drogopedia.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfEs peligroso mezclar Diazepam y Alcohol? | Drogopedia","og_description":"Mezclar Diazepam y Alcohol es muy peligroso para tu salud. Consulta efectos, interacciones y precauciones en la gu\u00eda Mezclas y Riesgos de Drogopedia.","og_url":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/","og_site_name":"Drogopedia: Mezclas y Riesgos - Gu\u00eda Interactiva","article_published_time":"2024-11-18T08:56:51+00:00","article_modified_time":"2026-06-17T11:47:37+00:00","og_image":[{"width":2400,"height":1350,"url":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-content\/uploads\/2024\/08\/1200x675.png","type":"image\/png"}],"author":"Drogopedia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"drogo_nsue"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/#article","isPartOf":{"@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/"},"author":{"name":"drogo_nsue","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#\/schema\/person\/13be64b3278cf1ee37796630f2b7001c"},"headline":"Diazepam y Alcohol","datePublished":"2024-11-18T08:56:51+00:00","dateModified":"2026-06-17T11:47:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/"},"wordCount":151,"publisher":{"@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#organization"},"articleSection":["Depresoras"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/","url":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/","name":"\u00bfEs peligroso mezclar Diazepam y Alcohol? | Drogopedia","isPartOf":{"@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#website"},"datePublished":"2024-11-18T08:56:51+00:00","dateModified":"2026-06-17T11:47:37+00:00","description":"Mezclar Diazepam y Alcohol es muy peligroso para tu salud. Consulta efectos, interacciones y precauciones en la gu\u00eda Mezclas y Riesgos de Drogopedia.","breadcrumb":{"@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/diazepam-y-alcohol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/"},{"@type":"ListItem","position":2,"name":"Diazepam y Alcohol"}]},{"@type":"WebSite","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#website","url":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/","name":"Drogopedia: Mezclas y Riesgos. Gu\u00eda interactiva","description":"Anticipa los principales riesgos y efectos de la mezcla de drogas psicoactivas y toma precauciones ante su consumo.","publisher":{"@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#organization"},"alternateName":"Drogopedia: Mezclas y Riesgos","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#organization","name":"Drogopedia: Mezclas y Riesgos","url":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#\/schema\/logo\/image\/","url":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-content\/uploads\/2024\/08\/696x696.png","contentUrl":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-content\/uploads\/2024\/08\/696x696.png","width":1392,"height":1392,"caption":"Drogopedia: Mezclas y Riesgos"},"image":{"@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/#\/schema\/person\/13be64b3278cf1ee37796630f2b7001c","name":"drogo_nsue","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/59faaca438de241bae8c733c27d18d29a2c31c0710a0b77c9fdeabd7e96ff0b8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/59faaca438de241bae8c733c27d18d29a2c31c0710a0b77c9fdeabd7e96ff0b8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/59faaca438de241bae8c733c27d18d29a2c31c0710a0b77c9fdeabd7e96ff0b8?s=96&d=mm&r=g","caption":"drogo_nsue"}}]}},"_links":{"self":[{"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/posts\/1046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/comments?post=1046"}],"version-history":[{"count":1,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/posts\/1046\/revisions"}],"predecessor-version":[{"id":1047,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/posts\/1046\/revisions\/1047"}],"wp:attachment":[{"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/media?parent=1046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/categories?post=1046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/tags?post=1046"},{"taxonomy":"sustancias","embeddable":true,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/sustancias?post=1046"},{"taxonomy":"riesgo","embeddable":true,"href":"https:\/\/www.ladrogopedia.com\/mezclas-y-riesgos\/wp-json\/wp\/v2\/riesgo?post=1046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}